{"id":296,"date":"2019-12-02T16:55:41","date_gmt":"2019-12-02T19:55:41","guid":{"rendered":"https:\/\/criticanoespecializada.ml\/?p=296"},"modified":"2021-07-21T23:18:50","modified_gmt":"2021-07-22T02:18:50","slug":"battle-for-azeroth-wow","status":"publish","type":"post","link":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/","title":{"rendered":"Battle for Azeroth"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Battle for Azeroth &#8211; WoW<\/h2>\n\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de <\/span><b><i>World of Warcraft<\/i><\/b><i><span style=\"font-weight: 400;\">, <\/span><\/i><b><i>Shadowlands<\/i><\/b><span style=\"font-weight: 400;\">. Por fin terminaron las especulaciones, se confirmaron sospechas, y no podemos m\u00e1s de la ansiedad. Sin embargo, <\/span><b><i>Battle for Azeroth<\/i><\/b><span style=\"font-weight: 400;\"> a\u00fan no termina, tenemos el parche 8.3 a la vuelta de la esquina y me parece oportuno hacer una mirada retrospectiva a lo que fue la \u00faltima expansi\u00f3n del MMO m\u00e1s popular de la comunidad gamer.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/criticanoespecializada.ml\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_-1024x576.jpg\" alt=\"Battle for Azeroth - Wow\" class=\"wp-image-297\" title=\"\" srcset=\"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_-1024x576.jpg 1024w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_-300x169.jpg 300w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_-768x432.jpg 768w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_-1536x864.jpg 1536w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Battle for Azeroth &#8211; WoW<\/figcaption><\/figure>\n\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La historia comienza poniendo en agenda nuevamente el enfrentamiento entre las dos facciones principales. Esa pel\u00edcula ya la vimos varias veces y no tiene nada de innovador. La Horda (liderada por <\/span><b><i>Sylvanas Birsaveloz<\/i><\/b><span style=\"font-weight: 400;\">) y la Alianza (bajo el comando del rey <\/span><b><i>Anduin Wrynn<\/i><\/b><span style=\"font-weight: 400;\">) parecieran tener una relaci\u00f3n t\u00f3xica en la que ninguna puede dejar a la otra tranquila. Pero acept\u00e9moslo, nos gusta tener un poco de drama en nuestras vidas, incluso en las virtuales, y de vez en cuando, reavivar esa chispa que marca la diferencia entre ambas facciones, sienta bien (al JcJ, sobre todo).&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><br><span style=\"font-weight: 400;\">Desde la jugabilidad, no hubieron muchos cambios ni mejoras trascendentales. Con mucho pesar nos vimos forzados a deshacernos de nuestra querida arma de artefacto, que nos acompa\u00f1\u00f3 durante la expansi\u00f3n anterior, y a la que tanto alimentamos con interminables farmeos de poder de artefacto. El hecho de tener un arma para cada especializaci\u00f3n que se pueda personalizar y el modo en que se vincul\u00f3 con el lore del juego, gener\u00f3 un sistema muy bien pensado para tirarlo por la borda en el nuevo parche (\u00bfpor qu\u00e9, Blizzard&#8230;?, \u00bfpor qu\u00e9?). Para conformarnos, nos entregaron el coraz\u00f3n de <\/span><b>Azeroth.<\/b><span style=\"font-weight: 400;\"> Un collar especial que contiene la energ\u00eda del mundo y que se alimenta de fragmentos de <\/span><b><i>azerita<\/i><\/b><span style=\"font-weight: 400;\">. Conforme sub\u00eda el nivel del coraz\u00f3n, \u00edbamos potenciando y destrabando nuevas combinaciones de habilidades para las piezas de armadura vinculadas al collar: casco, hombreras y pechera. Este m\u00e9todo result\u00f3 un tanto rebuscado, sin dejar de ser m\u00e1s de lo mismo: otra b\u00fasqueda constante de poder de artefacto para potenciar el equipo. En el parche 8.2, introdujeron el equipo <\/span><b><i>Bent\u00f3nico<\/i><\/b><span style=\"font-weight: 400;\">, mejorable hasta cierto nivel de \u00edtem. Pero una vez m\u00e1s, no termin\u00f3 de convencernos.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"642\" src=\"https:\/\/criticanoespecializada.ml\/wp-content\/uploads\/2019\/12\/IMG.2.Sistema-de-armadura-de-azerita-1024x642.jpg\" alt=\"\" class=\"wp-image-298\" title=\"\" srcset=\"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.2.Sistema-de-armadura-de-azerita-1024x642.jpg 1024w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.2.Sistema-de-armadura-de-azerita-300x188.jpg 300w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.2.Sistema-de-armadura-de-azerita-768x481.jpg 768w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.2.Sistema-de-armadura-de-azerita-1536x963.jpg 1536w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.2.Sistema-de-armadura-de-azerita.jpg 1551w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Battle for Azeroth &#8211; WoW<\/figcaption><\/figure>\n\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El modo guerra estuvo muy bien. Permiti\u00f3 a los usuarios activar o desactivar la opci\u00f3n de <\/span><i><span style=\"font-weight: 400;\">jugador contra jugador<\/span><\/i><span style=\"font-weight: 400;\"> en el mundo abierto y acceder a recompensas especiales. <\/span><b><i>La Horda<\/i><\/b><span style=\"font-weight: 400;\"> y la <\/span><b><i>Alianza<\/i><\/b><span style=\"font-weight: 400;\"> estaban en plena guerra, y los jugadores tuvieron la oportunidad de sentirse m\u00e1s parte de ella que nunca. Las expediciones insulares me resultaron entretenidas, una especie de gesta de tres jugadores cuya finalidad era recaudar determinada cantidad de <\/span><b><i>azerita<\/i><\/b> <span style=\"font-weight: 400;\">antes que la facci\u00f3n contraria. Sin embargo las recompensas no fueron lo suficientemente motivadoras para que tomen protagonismo. Continuaron con las cl\u00e1sicas mazmorras y bandas, con mec\u00e1nicas mucho m\u00e1s divertidas e intuitivas, pero sin perder complejidad.&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Puede que <\/span><b>Battle for Azeroth<\/b><span style=\"font-weight: 400;\"> no haya sido la mejor expansi\u00f3n en cuanto a jugabilidad se refiere, incluso fue bastante criticada por los jugadores que acompa\u00f1an la historia desde las primeras entregas. Pero hay algunas cosas que Blizzard hizo muy bien. En primer lugar, la ambientaci\u00f3n, tanto musical como visualmente. Los mapas se recorren acompa\u00f1ados por una banda sonora impecable que transmite el concepto principal de cada una de las zonas.&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los NPC (personajes no jugadores) pasaron de ser simples figuras distribuidas por ac\u00e1 y por all\u00e1 con alg\u00fan que otro movimiento, a interactuar con el entorno de una forma mucho m\u00e1s v\u00edvida. Cada facci\u00f3n tuvo su est\u00e9tica bien definida. Ciudad portuaria y mercantil con influencias de la pirater\u00eda para la Alianza. Mientras que la horda desembarc\u00f3 en un imperio Troll, con remanentes del per\u00edodo prehisp\u00e1nico en Mesoam\u00e9rica, en conjunto con dinosaurios merodeando por pantanos (un tanto raro, incre\u00edble, pero funcion\u00f3). La campa\u00f1a de guerra estuvo muy bien lograda. Los ataques a las zonas enemigas, sumados a la posibilidad de realizar JcJ activo ya sea atacando o defendiendo, dieron el toque ideal para generar un clima de guerra perfecto.&nbsp;<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/criticanoespecializada.ml\/wp-content\/uploads\/2019\/12\/IMG.3.Capital-Alianza-1024x576.jpg\" alt=\"\" class=\"wp-image-299\" title=\"\" srcset=\"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.3.Capital-Alianza-1024x576.jpg 1024w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.3.Capital-Alianza-300x169.jpg 300w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.3.Capital-Alianza-768x432.jpg 768w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.3.Capital-Alianza-1536x864.jpg 1536w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.3.Capital-Alianza.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Para la Horda, tuvo una vuelta de tuerca m\u00e1s; empiezan cumpliendo las \u00f3rdenes de una jefa de guerra con pol\u00edticas bastante cuestionables, y luego, a su vez, trabajar\u00edan en secreto con una resistencia que supo darse cuenta a tiempo de que se estaban destruyendo a s\u00ed mismos, y que los planes de <\/span><b><i>Sylvanas <\/i><\/b><span style=\"font-weight: 400;\">nada ten\u00edan que ver con el bien de su gente ni del mundo como lo conoc\u00edan. En general, fueron capaces de que seamos a\u00fan m\u00e1s parte de la historia, de forma muy natural, ya sea presenciando escenas importantes entre personajes principales, o en cinem\u00e1ticas que inclu\u00edan a nuestro adalid como uno m\u00e1s de la batalla. Hasta ahora solo hab\u00edamos sidos meros ejecutores, y los personajes del juego se llevaban todos los laureles.&nbsp;<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/criticanoespecializada.ml\/wp-content\/uploads\/2019\/12\/IMG.4.Capital-Horda-1024x576.jpg\" alt=\"\" class=\"wp-image-300\" title=\"\" srcset=\"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.4.Capital-Horda-1024x576.jpg 1024w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.4.Capital-Horda-300x169.jpg 300w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.4.Capital-Horda-768x432.jpg 768w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.4.Capital-Horda-1536x864.jpg 1536w, https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.4.Capital-Horda.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Battle for Azeroth &#8211; WoW<\/figcaption><\/figure>\n\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Probablemente, los jugadores m\u00e1s experimentados no se conformen con meras cuestiones est\u00e9ticas o narrativas para hacer un juicio de valor de la expansi\u00f3n, pero vale la pena destacarlas. El n\u00famero de usuarios activos fue disminuyendo conforme pasaron los meses, y muchos temieron que se cancelara antes de tiempo o incluso que llegue el fin de <\/span><b><i>World of Warcraft<\/i><\/b><span style=\"font-weight: 400;\">. Sin embargo a los fan\u00e1ticos suele picarles el bichito de la nostalgia m\u00e1s de lo que les gustar\u00eda admitir. Y siempre vamos a encontrar un motivo para volver a adentrarnos en el vasto mundo de <\/span><b><i>Azeroth<\/i><\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><br \/><br \/><span style=\"font-weight: 400;\">Para enterarte de mis novedades y seguir mi trabajo, entr\u00e1 en <\/span><span style=\"font-weight: 400;\">\u00a0<a href=\"https:\/\/www.instagram.com\/roslight.year\/\" target=\"_blank\" rel=\"noopener noreferrer\">Roslight Year<\/a><\/span><\/p>\n\n\n\n<h4 class=\"has-text-align-right wp-block-heading\"><em>Por <a href=\"https:\/\/criticanoespecializada.com.ar\/en\/rosario-fernandez\/\">Rosario Fern\u00e1ndez<\/a><\/em><\/h4>","protected":false},"excerpt":{"rendered":"<p>Battle for Azeroth &#8211; WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa:&hellip; <\/p>","protected":false},"author":11,"featured_media":297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAownYrbCw:productID":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-no-tan-gamer"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Battle for Azeroth - WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de World of Warcraft, Shadowlands. Por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rosario Fern\u00e1ndez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CnE - Cr\u00edtica no Especializada - Portal de entretenimiento\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Battle for Azeroth - CnE\" \/>\n\t\t<meta property=\"og:description\" content=\"Battle for Azeroth - WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de World of Warcraft, Shadowlands. Por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-02T19:55:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-07-22T02:18:50+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/critica.no.especializada\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@CnE_Revista\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Battle for Azeroth - CnE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Battle for Azeroth - WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de World of Warcraft, Shadowlands. Por\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@CnE_Revista\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#blogposting\",\"name\":\"Battle for Azeroth - CnE\",\"headline\":\"Battle for Azeroth\",\"author\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/author\\\/rosario\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/IMG.1.Mapa_.jpg\",\"width\":1920,\"height\":1080},\"datePublished\":\"2019-12-02T16:55:41-03:00\",\"dateModified\":\"2021-07-21T23:18:50-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#webpage\"},\"articleSection\":\"No tan Gamer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/#listItem\",\"name\":\"VideoJuegos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/#listItem\",\"position\":2,\"name\":\"VideoJuegos\",\"item\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/no-tan-gamer\\\/#listItem\",\"name\":\"No tan Gamer\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/no-tan-gamer\\\/#listItem\",\"position\":3,\"name\":\"No tan Gamer\",\"item\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/no-tan-gamer\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#listItem\",\"name\":\"Battle for Azeroth\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/#listItem\",\"name\":\"VideoJuegos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#listItem\",\"position\":4,\"name\":\"Battle for Azeroth\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/category\\\/videojuegos\\\/no-tan-gamer\\\/#listItem\",\"name\":\"No tan Gamer\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#organization\",\"name\":\"CnE\",\"description\":\"Cr\\u00edtica no Especializada - Portal de entretenimiento\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CNE-1.png\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#organizationLogo\",\"width\":1104,\"height\":847,\"caption\":\"LOGO-critica\"},\"image\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/critica.no.especializada\",\"https:\\\/\\\/twitter.com\\\/CnE_Revista\",\"https:\\\/\\\/www.instagram.com\\\/critica.no.especializada\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/author\\\/rosario\\\/#author\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/author\\\/rosario\\\/\",\"name\":\"Rosario Fern\\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef7215f22647b9b51ea1d99ac3fdad8057b396cd2e9024b4d9afa95b0a592b98?s=96&d=retro&r=g\",\"width\":96,\"height\":96,\"caption\":\"Rosario Fern\\u00e1ndez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#webpage\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/\",\"name\":\"Battle for Azeroth - CnE\",\"description\":\"Battle for Azeroth - WoW Otro a\\u00f1o que se termina, otra Blizzcon que lleg\\u00f3 y se fue; y para los fan\\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\\u00f3 (o mejor dicho, confirm\\u00f3) el t\\u00edtulo de la pr\\u00f3xima expansi\\u00f3n de World of Warcraft, Shadowlands. Por\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/author\\\/rosario\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/author\\\/rosario\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/IMG.1.Mapa_.jpg\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/battle-for-azeroth-wow\\\/#mainImage\"},\"datePublished\":\"2019-12-02T16:55:41-03:00\",\"dateModified\":\"2021-07-21T23:18:50-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/\",\"name\":\"CnE\",\"description\":\"Cr\\u00edtica no Especializada - Portal de entretenimiento\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Battle for Azeroth - CnE","description":"Battle for Azeroth - WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de World of Warcraft, Shadowlands. Por","canonical_url":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#blogposting","name":"Battle for Azeroth - CnE","headline":"Battle for Azeroth","author":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/author\/rosario\/#author"},"publisher":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_.jpg","width":1920,"height":1080},"datePublished":"2019-12-02T16:55:41-03:00","dateModified":"2021-07-21T23:18:50-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#webpage"},"isPartOf":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#webpage"},"articleSection":"No tan Gamer"},{"@type":"BreadcrumbList","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en#listItem","position":1,"name":"Home","item":"https:\/\/criticanoespecializada.com.ar\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/#listItem","name":"VideoJuegos"}},{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/#listItem","position":2,"name":"VideoJuegos","item":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/no-tan-gamer\/#listItem","name":"No tan Gamer"},"previousItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/no-tan-gamer\/#listItem","position":3,"name":"No tan Gamer","item":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/no-tan-gamer\/","nextItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#listItem","name":"Battle for Azeroth"},"previousItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/#listItem","name":"VideoJuegos"}},{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#listItem","position":4,"name":"Battle for Azeroth","previousItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/no-tan-gamer\/#listItem","name":"No tan Gamer"}}]},{"@type":"Organization","@id":"https:\/\/criticanoespecializada.com.ar\/en\/#organization","name":"CnE","description":"Cr\u00edtica no Especializada - Portal de entretenimiento","url":"https:\/\/criticanoespecializada.com.ar\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/11\/CNE-1.png","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#organizationLogo","width":1104,"height":847,"caption":"LOGO-critica"},"image":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/critica.no.especializada","https:\/\/twitter.com\/CnE_Revista","https:\/\/www.instagram.com\/critica.no.especializada\/"]},{"@type":"Person","@id":"https:\/\/criticanoespecializada.com.ar\/en\/author\/rosario\/#author","url":"https:\/\/criticanoespecializada.com.ar\/en\/author\/rosario\/","name":"Rosario Fern\u00e1ndez","image":{"@type":"ImageObject","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ef7215f22647b9b51ea1d99ac3fdad8057b396cd2e9024b4d9afa95b0a592b98?s=96&d=retro&r=g","width":96,"height":96,"caption":"Rosario Fern\u00e1ndez"}},{"@type":"WebPage","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#webpage","url":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/","name":"Battle for Azeroth - CnE","description":"Battle for Azeroth - WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de World of Warcraft, Shadowlands. Por","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/#website"},"breadcrumb":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#breadcrumblist"},"author":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/author\/rosario\/#author"},"creator":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/author\/rosario\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/12\/IMG.1.Mapa_.jpg","@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/#mainImage"},"datePublished":"2019-12-02T16:55:41-03:00","dateModified":"2021-07-21T23:18:50-03:00"},{"@type":"WebSite","@id":"https:\/\/criticanoespecializada.com.ar\/en\/#website","url":"https:\/\/criticanoespecializada.com.ar\/en\/","name":"CnE","description":"Cr\u00edtica no Especializada - Portal de entretenimiento","inLanguage":"en-US","publisher":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"CnE - Cr\u00edtica no Especializada - Portal de entretenimiento","og:type":"article","og:title":"Battle for Azeroth - CnE","og:description":"Battle for Azeroth - WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de World of Warcraft, Shadowlands. Por","og:url":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/","article:published_time":"2019-12-02T19:55:41+00:00","article:modified_time":"2021-07-22T02:18:50+00:00","article:publisher":"https:\/\/www.facebook.com\/critica.no.especializada","twitter:card":"summary_large_image","twitter:site":"@CnE_Revista","twitter:title":"Battle for Azeroth - CnE","twitter:description":"Battle for Azeroth - WoW Otro a\u00f1o que se termina, otra Blizzcon que lleg\u00f3 y se fue; y para los fan\u00e1ticos de la franquicia, este evento solo significa una cosa: el anuncio del tan esperado nuevo contenido. Blizzard revel\u00f3 (o mejor dicho, confirm\u00f3) el t\u00edtulo de la pr\u00f3xima expansi\u00f3n de World of Warcraft, Shadowlands. Por","twitter:creator":"@CnE_Revista"},"aioseo_meta_data":{"post_id":"296","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-19 18:26:43","updated":"2025-06-04 03:45:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/criticanoespecializada.com.ar\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/\" title=\"VideoJuegos\">VideoJuegos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/no-tan-gamer\/\" title=\"No tan Gamer\">No tan Gamer<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBattle for Azeroth\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/criticanoespecializada.com.ar\/en"},{"label":"VideoJuegos","link":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/"},{"label":"No tan Gamer","link":"https:\/\/criticanoespecializada.com.ar\/en\/category\/videojuegos\/no-tan-gamer\/"},{"label":"Battle for Azeroth","link":"https:\/\/criticanoespecializada.com.ar\/en\/battle-for-azeroth-wow\/"}],"_links":{"self":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/posts\/296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/comments?post=296"}],"version-history":[{"count":4,"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/posts\/296\/revisions"}],"predecessor-version":[{"id":1389,"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/posts\/296\/revisions\/1389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/media\/297"}],"wp:attachment":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/media?parent=296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/categories?post=296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags?post=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}