{"id":405,"count":1,"description":"","link":"https:\/\/criticanoespecializada.com.ar\/en\/tag\/cine-arabe\/","name":"Cine \u00c1rabe","slug":"cine-arabe","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/criticanoespecializada.com.ar\/en\/tag\/cine-arabe\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/405\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/tag\\\/cine-arabe\\\/#listItem\",\"name\":\"Cine \\u00c1rabe\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/tag\\\/cine-arabe\\\/#listItem\",\"position\":2,\"name\":\"Cine \\u00c1rabe\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/405\\\/#collectionpage\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/405\\\/\",\"name\":\"Cine \\u00c1rabe - CnE\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/405\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#organization\",\"name\":\"CnE\",\"description\":\"Cr\\u00edtica no Especializada - Portal de entretenimiento\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/CNE-1.png\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/405\\\/#organizationLogo\",\"width\":1104,\"height\":847,\"caption\":\"LOGO-critica\"},\"image\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/405\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/critica.no.especializada\",\"https:\\\/\\\/twitter.com\\\/CnE_Revista\",\"https:\\\/\\\/www.instagram.com\\\/critica.no.especializada\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/\",\"name\":\"CnE\",\"description\":\"Cr\\u00edtica no Especializada - Portal de entretenimiento\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/criticanoespecializada.com.ar\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cine \u00c1rabe - CnE","description":"","canonical_url":"https:\/\/criticanoespecializada.com.ar\/en\/tag\/cine-arabe\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags\/405\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en#listItem","position":1,"name":"Home","item":"https:\/\/criticanoespecializada.com.ar\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/tag\/cine-arabe\/#listItem","name":"Cine \u00c1rabe"}},{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en\/tag\/cine-arabe\/#listItem","position":2,"name":"Cine \u00c1rabe","previousItem":{"@type":"ListItem","@id":"https:\/\/criticanoespecializada.com.ar\/en#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags\/405\/#collectionpage","url":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags\/405\/","name":"Cine \u00c1rabe - CnE","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/#website"},"breadcrumb":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags\/405\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/criticanoespecializada.com.ar\/en\/#organization","name":"CnE","description":"Cr\u00edtica no Especializada - Portal de entretenimiento","url":"https:\/\/criticanoespecializada.com.ar\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/criticanoespecializada.com.ar\/wp-content\/uploads\/2019\/11\/CNE-1.png","@id":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags\/405\/#organizationLogo","width":1104,"height":847,"caption":"LOGO-critica"},"image":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags\/405\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/critica.no.especializada","https:\/\/twitter.com\/CnE_Revista","https:\/\/www.instagram.com\/critica.no.especializada\/"]},{"@type":"WebSite","@id":"https:\/\/criticanoespecializada.com.ar\/en\/#website","url":"https:\/\/criticanoespecializada.com.ar\/en\/","name":"CnE","description":"Cr\u00edtica no Especializada - Portal de entretenimiento","inLanguage":"en-US","publisher":{"@id":"https:\/\/criticanoespecializada.com.ar\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/criticanoespecializada.com.ar\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCine \u00c1rabe\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/criticanoespecializada.com.ar\/en"},{"label":"Cine \u00c1rabe","link":"https:\/\/criticanoespecializada.com.ar\/en\/tag\/cine-arabe\/"}],"_links":{"self":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags\/405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/criticanoespecializada.com.ar\/en\/wp-json\/wp\/v2\/posts?tags=405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}